{"id":3230,"date":"2025-11-20T13:57:52","date_gmt":"2025-11-20T13:57:52","guid":{"rendered":"https:\/\/romexstays.com\/?post_type=events&#038;p=3230"},"modified":"2026-02-03T13:39:42","modified_gmt":"2026-02-03T13:39:42","slug":"feiern-sie-weihnachten-im-restaurant-jakob","status":"publish","type":"events","link":"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/","title":{"rendered":"Feiern Sie Weihnachten im Restaurant JAKOB"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3230\" class=\"elementor elementor-3230 elementor-579\" data-elementor-post-type=\"events\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3538194 e-flex e-con-boxed e-con e-parent\" data-id=\"3538194\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5ee218 elementor-widget elementor-widget-image\" data-id=\"f5ee218\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-683x1024.jpg\" class=\"attachment-large size-large wp-image-3228\" alt=\"\" srcset=\"https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-683x1024.jpg 683w, https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-200x300.jpg 200w, https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-768x1152.jpg 768w, https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-1024x1536.jpg 1024w, https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-1366x2048.jpg 1366w, https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37e97be elementor-widget elementor-widget-text-editor\" data-id=\"37e97be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>Feiern Sie Weihnachten stilvoll im Restaurant JAKOB im Hotel Jakobwirt<\/b><\/h3><p><span style=\"font-weight: 400;\">Die Feiertage sind eine Zeit, um zusammenzukommen, gutes Essen zu genie\u00dfen und besondere Momente mit Familie und Freunden zu teilen. In diesem Jahr l\u00e4dt Sie das Hotel Jakobwirt ein, die Weihnachtsstimmung stilvoll zu erleben, mit einem exklusiven Weihnachtsdinner im eleganten Restaurant JAKOB. Mitten im Herzen von Westendorf bietet JAKOB die perfekte Kombination aus Luxus und kulinarischen Highlights.<\/span><\/p><h3><b>Ein 4-G\u00e4nge-Weihnachtsdinner zum Tr\u00e4umen<\/b><\/h3><p><span style=\"font-weight: 400;\">Das Restaurant JAKOB ist bekannt f\u00fcr seine raffinierte K\u00fcche und stilvolle Atmosph\u00e4re. F\u00fcr den ersten Weihnachtstag hat der K\u00fcchenchef ein spezielles 4-G\u00e4nge-Men\u00fc zusammengestellt, das die Aromen der Saison feiert. Jedes Gericht wird mit Sorgfalt und Pr\u00e4zision zubereitet und verwendet nur die besten Zutaten.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\">Das Men\u00fc kostet 37,50 \u20ac pro Person und ist sowohl f\u00fcr Hotelg\u00e4ste als auch f\u00fcr externe Besucher verf\u00fcgbar. Sie m\u00fcssen also nicht im Hotel \u00fcbernachten, um dieses festliche Dinner zu genie\u00dfen.<\/span><\/p><h3><b>Das perfekte Weinarrangement<\/b><\/h3><p><b><\/b><span style=\"font-weight: 400;\">Zu einem besonderen Weihnachtsdinner geh\u00f6rt selbstverst\u00e4ndlich eine passende Weinbegleitung. Das Restaurant JAKOB bietet eine sorgf\u00e4ltig ausgew\u00e4hlte Auswahl an Weinen, von lokalen Favoriten bis zu internationalen Spitzenweinen. Das Personal ber\u00e4t Sie gerne bei der idealen Weinwahl. Ob Sie einen vollmundigen Rotwein zum reichhaltigen Hauptgericht oder einen frischen Wei\u00dfwein zu einer leichten Fischspeise bevorzugen \u2013 das Weinarrangement hebt Ihr Dinner auf ein neues Niveau.<\/span><\/p><h3><b>Die festliche Atmosph\u00e4re von Westendorf<\/b><b><br \/><\/b><\/h3><p><span style=\"font-weight: 400;\">Westendorf ist eines der sch\u00f6nsten D\u00f6rfer in den Kitzb\u00fcheler Alpen und bietet w\u00e4hrend der Weihnachtszeit eine magische Stimmung. Geschm\u00fcckte Stra\u00dfen, funkelnde Lichter und \u00fcberall festliche Stimmung schaffen die perfekte Kulisse f\u00fcr einen entspannten und feierlichen Aufenthalt. Ein Dinner im Restaurant JAKOB ist somit nicht nur ein kulinarisches Erlebnis, sondern auch eine Gelegenheit, die lokale Kultur und Weihnachtstraditionen zu erleben.<\/span><\/p><p><span style=\"font-weight: 400;\">F\u00fcr G\u00e4ste, die im Hotel \u00fcbernachten m\u00f6chten, bietet das Hotel Jakobwirt komfortable und stilvolle Zimmer und Suiten, jeweils mit modernen Annehmlichkeiten und einer warmen, einladenden Atmosph\u00e4re. Das Adults-Only-Konzept sorgt f\u00fcr eine ruhige Umgebung, in der Sie sich vollst\u00e4ndig entspannen k\u00f6nnen. Nach Ihrem Weihnachtsdinner k\u00f6nnen Sie in Ihr Zimmer zur\u00fcckkehren und den perfekten Abend ausklingen lassen, vielleicht noch bei einem Glas Wein oder einem warmen Getr\u00e4nk.<\/span><\/p><h3><b>Aktivit\u00e4ten vor und nach dem Dinner<\/b><b><br \/><\/b><\/h3><p><span style=\"font-weight: 400;\">Neben einem unvergesslichen Weihnachtsdinner bietet Westendorf zahlreiche Aktivit\u00e4ten, um Ihre Feiertage perfekt zu gestalten. F\u00fcr sportliche G\u00e4ste liegen die Pisten von SkiWelt nur wenige Gehminuten vom Hotel entfernt. Ob erfahrener Skifahrer oder Anf\u00e4nger, die Berge rund um Westendorf bieten f\u00fcr jeden etwas.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\">F\u00fcr diejenigen, die Entspannung suchen, gibt es im Hotel und in der Umgebung viele M\u00f6glichkeiten, zur Ruhe zu kommen. Machen Sie einen Spaziergang durch verschneite W\u00e4lder, besuchen Sie die Wellnessbereiche des Hotels oder genie\u00dfen Sie eine hei\u00dfe Schokolade mit Sahne in der gem\u00fctlichen Hotellobby. So verbinden Sie ein k\u00f6stliches Dinner mit einem ganzen Tag in der frischen Bergluft oder einem entspannten Nachmittag.<\/span><\/p><h3><b>Rechtzeitig reservieren<\/b><b><br \/><\/b><\/h3><p><span style=\"font-weight: 400;\">Das Weihnachtsdinner im Restaurant JAKOB ist sehr beliebt und die Tische sind schnell ausgebucht. Es wird daher empfohlen, fr\u00fchzeitig zu reservieren, um einen Platz zu sichern. Sie k\u00f6nnen das Hotel einfach telefonisch oder per E-Mail kontaktieren. Das Team des Jakobwirt Hotels steht bereit, um alle Fragen zu beantworten und Ihnen bei der Planung eines perfekten Abends zu helfen.<\/span><\/p><h3><b>Ein unvergessliches Weihnachten<\/b><b><br \/><\/b><\/h3><p><span style=\"font-weight: 400;\">Ob Sie ein romantisches Dinner mit Ihrem Partner, einen geselligen Abend mit Freunden oder ein besonderes Familientreffen planen, das Restaurant JAKOB bietet die ideale Kulisse. Mit einer Kombination aus k\u00f6stlichen Gerichten, einer umfangreichen Weinauswahl und einer gem\u00fctlichen Atmosph\u00e4re wird Ihr Weihnachtsabend zu einem unvergesslichen Erlebnis.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\">Das Weihnachtsdinner ist nicht nur ein kulinarisches Highlight, sondern auch eine Gelegenheit, innezuhalten und sich auf das Wesentliche zu besinnen: Zusammenkommen, genie\u00dfen und Erinnerungen schaffen. Im Hotel Jakobwirt und Restaurant JAKOB sind Sie f\u00fcr einen Abend voller W\u00e4rme, Geschmack und Freude bestens versorgt.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Genie\u00dfen Sie ein stimmungsvolles Weihnachtsdinner im stilvollen Restaurant JAKOB. Lassen Sie sich von einem sorgf\u00e4ltig zusammengestellten 4-G\u00e4nge-Men\u00fc f\u00fcr 37,50 \u20ac pro Person verw\u00f6hnen, mit k\u00f6stlichen saisonalen Gerichten, die die Feiertage besonders machen. Abgerundet wird Ihr Dinner von einer hervorragenden Auswahl an Weinen. Reservieren Sie rechtzeitig und erleben Sie ein unvergessliches kulinarisches Weihnachten.<\/p>\n","protected":false},"featured_media":3228,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"event_tag":[],"class_list":["post-3230","events","type-events","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weihnachten im Restaurant Jakob feiern \u2013 Festliches Men\u00fc<\/title>\n<meta name=\"description\" content=\"Feiern Sie Weihnachten im Restaurant Jakob. Genie\u00dfen Sie festliche Men\u00fcs und traditionelle Tiroler Gastfreundschaft in gem\u00fctlicher Atmosph\u00e4re.Jetzt buchen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weihnachten im Restaurant Jakob feiern \u2013 Festliches Men\u00fc\" \/>\n<meta property=\"og:description\" content=\"Feiern Sie Weihnachten im Restaurant Jakob. Genie\u00dfen Sie festliche Men\u00fcs und traditionelle Tiroler Gastfreundschaft in gem\u00fctlicher Atmosph\u00e4re.Jetzt buchen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/\" \/>\n<meta property=\"og:site_name\" content=\"Romex Stays\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T13:39:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/events\\\/feiern-sie-weihnachten-im-restaurant-jakob\\\/\",\"url\":\"https:\\\/\\\/romexstays.com\\\/de\\\/events\\\/feiern-sie-weihnachten-im-restaurant-jakob\\\/\",\"name\":\"Weihnachten im Restaurant Jakob feiern \u2013 Festliches Men\u00fc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/events\\\/feiern-sie-weihnachten-im-restaurant-jakob\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/events\\\/feiern-sie-weihnachten-im-restaurant-jakob\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/romexstays.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Hotel-Jakobwirt-Christmas-scaled.jpg\",\"datePublished\":\"2025-11-20T13:57:52+00:00\",\"dateModified\":\"2026-02-03T13:39:42+00:00\",\"description\":\"Feiern Sie Weihnachten im Restaurant Jakob. Genie\u00dfen Sie festliche Men\u00fcs und traditionelle Tiroler Gastfreundschaft in gem\u00fctlicher Atmosph\u00e4re.Jetzt buchen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/events\\\/feiern-sie-weihnachten-im-restaurant-jakob\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/romexstays.com\\\/de\\\/events\\\/feiern-sie-weihnachten-im-restaurant-jakob\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/events\\\/feiern-sie-weihnachten-im-restaurant-jakob\\\/#primaryimage\",\"url\":\"https:\\\/\\\/romexstays.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Hotel-Jakobwirt-Christmas-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/romexstays.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Hotel-Jakobwirt-Christmas-scaled.jpg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/events\\\/feiern-sie-weihnachten-im-restaurant-jakob\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/romexstays.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feiern Sie Weihnachten im Restaurant JAKOB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/romexstays.com\\\/de\\\/\",\"name\":\"Romex Stays\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/romexstays.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/#organization\",\"name\":\"Romex Stays\",\"url\":\"https:\\\/\\\/romexstays.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/romexstays.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/romexstays.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo.svg\",\"width\":128,\"height\":56,\"caption\":\"Romex Stays\"},\"image\":{\"@id\":\"https:\\\/\\\/romexstays.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weihnachten im Restaurant Jakob feiern \u2013 Festliches Men\u00fc","description":"Feiern Sie Weihnachten im Restaurant Jakob. Genie\u00dfen Sie festliche Men\u00fcs und traditionelle Tiroler Gastfreundschaft in gem\u00fctlicher Atmosph\u00e4re.Jetzt buchen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/","og_locale":"de_DE","og_type":"article","og_title":"Weihnachten im Restaurant Jakob feiern \u2013 Festliches Men\u00fc","og_description":"Feiern Sie Weihnachten im Restaurant Jakob. Genie\u00dfen Sie festliche Men\u00fcs und traditionelle Tiroler Gastfreundschaft in gem\u00fctlicher Atmosph\u00e4re.Jetzt buchen!","og_url":"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/","og_site_name":"Romex Stays","article_modified_time":"2026-02-03T13:39:42+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/","url":"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/","name":"Weihnachten im Restaurant Jakob feiern \u2013 Festliches Men\u00fc","isPartOf":{"@id":"https:\/\/romexstays.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/#primaryimage"},"image":{"@id":"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/#primaryimage"},"thumbnailUrl":"https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-scaled.jpg","datePublished":"2025-11-20T13:57:52+00:00","dateModified":"2026-02-03T13:39:42+00:00","description":"Feiern Sie Weihnachten im Restaurant Jakob. Genie\u00dfen Sie festliche Men\u00fcs und traditionelle Tiroler Gastfreundschaft in gem\u00fctlicher Atmosph\u00e4re.Jetzt buchen!","breadcrumb":{"@id":"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/#primaryimage","url":"https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-scaled.jpg","contentUrl":"https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/Hotel-Jakobwirt-Christmas-scaled.jpg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/romexstays.com\/de\/events\/feiern-sie-weihnachten-im-restaurant-jakob\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/romexstays.com\/de\/"},{"@type":"ListItem","position":2,"name":"Feiern Sie Weihnachten im Restaurant JAKOB"}]},{"@type":"WebSite","@id":"https:\/\/romexstays.com\/de\/#website","url":"https:\/\/romexstays.com\/de\/","name":"Romex Stays","description":"","publisher":{"@id":"https:\/\/romexstays.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/romexstays.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/romexstays.com\/de\/#organization","name":"Romex Stays","url":"https:\/\/romexstays.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/romexstays.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/logo.svg","contentUrl":"https:\/\/romexstays.com\/wp-content\/uploads\/2025\/11\/logo.svg","width":128,"height":56,"caption":"Romex Stays"},"image":{"@id":"https:\/\/romexstays.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/romexstays.com\/de\/wp-json\/wp\/v2\/events\/3230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/romexstays.com\/de\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/romexstays.com\/de\/wp-json\/wp\/v2\/types\/events"}],"version-history":[{"count":4,"href":"https:\/\/romexstays.com\/de\/wp-json\/wp\/v2\/events\/3230\/revisions"}],"predecessor-version":[{"id":3235,"href":"https:\/\/romexstays.com\/de\/wp-json\/wp\/v2\/events\/3230\/revisions\/3235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/romexstays.com\/de\/wp-json\/wp\/v2\/media\/3228"}],"wp:attachment":[{"href":"https:\/\/romexstays.com\/de\/wp-json\/wp\/v2\/media?parent=3230"}],"wp:term":[{"taxonomy":"event_tag","embeddable":true,"href":"https:\/\/romexstays.com\/de\/wp-json\/wp\/v2\/event_tag?post=3230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}